{"id":144310,"date":"2018-06-18T16:16:41","date_gmt":"2018-06-18T19:16:41","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144310"},"modified":"2018-06-18T16:16:41","modified_gmt":"2018-06-18T19:16:41","slug":"previsao-do-tempo-sudeste-em-19-06-e-20-06","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/previsao-do-tempo-sudeste-em-19-06-e-20-06\/144310","title":{"rendered":"Previs\u00e3o do tempo Sudeste em 19\/06 e 20\/06"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26302 size-thumbnail\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-tempo-clima-temperatura--150x96.jpg\" alt=\"Previs\u00e3o do tempo para o Sudeste\" width=\"150\" height=\"96\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-tempo-clima-temperatura--150x96.jpg 150w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-tempo-clima-temperatura--250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-tempo-clima-temperatura-.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Previs\u00e3o do tempo<\/em><\/strong> na Regi\u00e3o <strong><em>Sudeste<\/em><\/strong>, em 19\/06\/2018:\u00a0No norte do ES haver\u00e1 muitas nuvens e chuvas isoladas. No leste da regi\u00e3o o dia ficar\u00e1 nublado com possibilidade de chuva. No sul de MG e no norte de SP haver\u00e1 nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva a partir da tarde. Nas demais \u00e1reas da regi\u00e3o o sol aparecer\u00e1 entre poucas nuvens. Temperatura est\u00e1vel.<\/p>\n<p>20\/06\/2018:\u00a0No norte de MG o sol aparecer\u00e1 entre nebulosidade vari\u00e1vel. No oeste de MG e norte de SP o sol predominar\u00e1. Nas demais \u00e1reas da regi\u00e3o o sol aparecer\u00e1 entre poucas nuvens. Temperatura est\u00e1vel.<\/p>\n<p>Previs\u00e3o do tempo CPTEC\/INPE\/MCTI<\/p>\n<p>&#8212;<br \/>\nO CPTEC (Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos) do INPE (Instituto Nacional de Pesquisas Espaciais) \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Com o novo supercomputador (CRAY XT6), rec\u00e9m adquirido, ser\u00e1 poss\u00edvel ao Centro melhorar a resolu\u00e7\u00e3o espacial dos modelos de previs\u00e3o de tempo, de clima sazonal, ambiental (qualidade do ar) e de proje\u00e7\u00f5es de cen\u00e1rios de mudan\u00e7as clim\u00e1ticas. O CPTEC j\u00e1 vem aperfei\u00e7oando seus modelos para que o novo supercomputador tamb\u00e9m possa gerar previs\u00f5es com mais dias de anteced\u00eancia, al\u00e9m de prever chuvas e eventos extremos com maior confiabilidade.<\/p>\n<p>O cluster UNA com 1100 processadores tem capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Tudo isso, significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Sudeste, em 19\/06\/2018:\u00a0No norte do ES haver\u00e1 muitas nuvens e chuvas isoladas. No leste da regi\u00e3o o dia ficar\u00e1 nublado com possibilidade de chuva. No sul de MG e no norte de SP haver\u00e1 nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva a partir da tarde. Nas demais \u00e1reas da [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[327],"tags":[475],"class_list":{"0":"post-144310","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-clima","7":"tag-previsao-tempo"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144310"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144310\/revisions"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}