{"id":144440,"date":"2018-06-20T15:29:16","date_gmt":"2018-06-20T18:29:16","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144440"},"modified":"2018-06-20T15:29:16","modified_gmt":"2018-06-20T18:29:16","slug":"resumo-novela-coracao-indomavel-21-06-otavinho-desaparece-da-fazenda","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/resumo-novela-coracao-indomavel-21-06-otavinho-desaparece-da-fazenda\/144440","title":{"rendered":"Resumo novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d 21\/06: Otavinho desaparece da fazenda"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-66161\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/coracao_indomavel_sbt_novela_resumo-150x112.jpg\" alt=\"\" width=\"150\" height=\"112\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/coracao_indomavel_sbt_novela_resumo-150x112.jpg 150w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/coracao_indomavel_sbt_novela_resumo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Resumo novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d 21\/06 <\/em><\/strong>: no cap\u00edtulo 114(*) da novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d, quinta-feira, 21 de junho, Jos\u00e9 Antonio diz a Esther que Bas\u00edlio foi quem tentou lhe matar. Basilio se entrega a pol\u00edcia dizendo que o ocorrido com Jos\u00e9 Antonio foi um problema entre homens. Of\u00e9lia diz a Ot\u00e1vio que Otavinho n\u00e3o est\u00e1 em casa. Ot\u00e1vio a pergunta por Simone. Of\u00e9lia responde que ela tamb\u00e9m n\u00e3o est\u00e1 em casa. Desesperado, Ot\u00e1vio diz a Of\u00e9lia que eles devem encontrar Simone, j\u00e1 que Otavinho deve estar com ela, e assim, correndo perigo. <\/p>\n<p>Ot\u00e1vio vasculha a fazenda atr\u00e1s de Simone e acaba encontrando a, curiosamente, em seu quarto. Ele pergunta sobre Otavinho e ela pergunta a quem ele se refere. Simone se desespera ao n\u00e3o lembrar de nada e pede a Ot\u00e1vio que fale o que est\u00e1 acontecendo. Maricruz diz a Nilda que a m\u00e3e de Mudinha possivelmente apareceu e que a mo\u00e7a est\u00e1 gr\u00e1vida e apaixonada. Maricruz apresenta Nilda a Mudinha como sendo sua m\u00e3e. Mudinha fica desconcertada. Maricruz diz a Perico que Nilda \u00e9 a m\u00e3e de Mudinha e ele se surpreende ao ver que ela \u00e9 uma senhora fina. <\/p>\n<p>Nilda pede a Mudinha que a perdoe por t\u00ea-la abandonado. Elas se abra\u00e7am. Nilda diz a Maricruz que n\u00e3o pode permitir que Mudinha siga com sua gravidez, j\u00e1 que ela corre risco de vida. Of\u00e9lia informa a Miguel sobre o desaparecimento de Otavinho. Nilda diz a Maricruz que deseja levar Mudinha com ela, e que n\u00e3o permitir\u00e1 que a filha fique com Perico. Confuso, Ot\u00e1vio pensa que se n\u00e3o foi Simone quem desapareceu com Otavinho, pode ter sido coisa de Maricruz.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Sinopse &#8211; Maria Alessandra Mendon\u00e7a Olivares, mais conhecida como Maricruz Olivares (Ana Brenda Contreras) vive com Ramiro (Ignacio L\u00f3pez Tarso), seu av\u00f4 materno, e com Soledad (Gaby Mellado), sua irm\u00e3 adotiva, que \u00e9 surda-muda e que foi abandonada quando pequena. Sua casa \u00e9 uma cabana situada em plena natureza, aos arredores da fazenda Narv\u00e1ez. Miguel (Ren\u00e9 Strickler) e Ot\u00e1vio (Daniel Arenas) s\u00e3o irm\u00e3os e donos da fazenda Narv\u00e1ez, que est\u00e1 hipotecada pela m\u00e1 administra\u00e7\u00e3o de Miguel, o irm\u00e3o mais velho. Ot\u00e1vio \u00e9 piloto e chega \u00e0 fazenda necessitado de dinheiro pois ficou sem trabalho e quer que as terras sejam vendidas, mas sem imaginar, logo vai esquecendo esse objetivo, pois descobre que a terra, a planta\u00e7\u00e3o e o trato com os trabalhadores, s\u00e3o motivo de paix\u00e3o para ele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d 21\/06 : no cap\u00edtulo 114(*) da novela \u201cCora\u00e7\u00e3o Indom\u00e1vel\u201d, quinta-feira, 21 de junho, Jos\u00e9 Antonio diz a Esther que Bas\u00edlio foi quem tentou lhe matar. Basilio se entrega a pol\u00edcia dizendo que o ocorrido com Jos\u00e9 Antonio foi um problema entre homens. Of\u00e9lia diz a Ot\u00e1vio que Otavinho n\u00e3o est\u00e1 em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[379,372,343],"tags":[441],"class_list":{"0":"post-144440","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-sbt","9":"category-televisao","10":"tag-resumo-do-dia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144440"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/66161"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}