{"id":144527,"date":"2018-06-21T17:54:13","date_gmt":"2018-06-21T20:54:13","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144527"},"modified":"2018-06-21T17:54:13","modified_gmt":"2018-06-21T20:54:13","slug":"resumo-novela-chiquititas-22-06-andreia-finge-passar-mal-e-se-afogar","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/resumo-novela-chiquititas-22-06-andreia-finge-passar-mal-e-se-afogar\/144527","title":{"rendered":"Resumo novela \u201cChiquititas\u201d 22\/06: Andreia finge passar mal e se afogar"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-49690\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/chiquititas1-150x112.jpg\" alt=\"chiquititas\" width=\"150\" height=\"112\" \/><strong><em>Resumo novela \u201cChiquititas\u201d 22\/06 <\/em><\/strong>: no cap\u00edtulo 464(*) da novela \u201cChiquititas\u201d, resumo de sexta-feira, 22 de junho, Vivi diz para Tati e Cris que encontrou com Cintia por acaso no shopping. Cris pergunta o motivo dela estar num site com Cintia. Vivi responde que n\u00e3o perderia a chance de aparecer na m\u00eddia. Tati diz que o pai dela n\u00e3o vai gostar nada disso. Vivi pede para elas n\u00e3o contarem nada. Mili liga para Mosca e conta que participar\u00e1 do concurso de talento. Marian escuta a conversa. Beto chega em casa e Clarita diz que est\u00e1 l\u00e1 para falar com ele. \u201cEu gosto de voc\u00ea Beto. Na verdade eu nunca deixei de gostar\u201d, revela Clarita, que se emociona. <\/p>\n<p>Beto diz que agora \u00e9 muito tarde e ele est\u00e1 feliz com \u00c9rica. Samuca, Binho e Thiago decidem jogar o videogame escondido durante a noite. No Samb\u00e3o, Eduarda fica enciumada e tenta chamar a aten\u00e7\u00e3o de Oscar, que dan\u00e7a com T\u00e1bata. Os meninos acabam dormindo enquanto jogam. Ana, Tati e Teca brigam com os tr\u00eas na manh\u00e3 seguinte. Carol conversa com o doutor Mendes e diz que n\u00e3o \u00e9 culpada pelo desvio do dinheiro da doa\u00e7\u00e3o. Mendes diz que acredita nela, mas sem provas n\u00e3o pode fazer nada e que Carmen j\u00e1 escolheu quem ser\u00e1 a nova diretora do orfanato, mas n\u00e3o pode revelar o nome. <\/p>\n<p>Junior brinca com Diego na praia. Eduarda se preocupa com sua apar\u00eancia. Shirley diz que ela est\u00e1 linda e que Oscar vai gostar dela da maneira que ela \u00e9. Junior diz que Andreia est\u00e1 com \u00f3tima apar\u00eancia e n\u00e3o parece doente. Andreia explica que os efeitos de sua doen\u00e7a s\u00e3o mais internos. Diego chama Junior para ver o castelo de areia que ele fez. Andreia vai at\u00e9 o mar, finge passar mal e se afogar. A mulher grita por Junior e deixa Diego desesperado no beira mar. Junior mergulha e tira Andreia do mar. Andreia desperta e acalma o filho.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cChiquititas\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Chiquititas gira em torno do orfanato Raio de Luz, que carrega em sua hist\u00f3ria um grande segredo envolvendo a fam\u00edlia e o dono do orfanato, Dr. Jos\u00e9 Ricardo Almeida Campos. Em um per\u00edodo anterior \u00e0 novela, exatos treze anos, sua filha Gabriela se apaixonou e ficou gr\u00e1vida de Miguel, filho de Valentina, empregada da casa dos Almeida Campos. Pouco depois, Jos\u00e9 Ricardo sequestrou sua neta, pois, como um homem conservador, ele n\u00e3o aceitava a ideia de que sua filha se envolvesse com um empregado. Como sua neta, Milena, apelidada como Mili, precisava de um lugar para morar, ele comprou um casar\u00e3o e fundou um orfanato, o Raio de Luz. <\/p>\n<p>Mili cresceu l\u00e1 com outras garotas que chegaram posteriormente: Bia, Ana, as irm\u00e3s Tati e Vivi, e Cris. Ao decorrer dos anos, elas se tornam uma fam\u00edlia. Elas s\u00e3o supervisionadas por Ernestina, zeladora do orfanato, e Chico, o cozinheiro amado pelas internas. Sofia, ex-governanta da fam\u00edlia Almeida Campos, \u00e9 a diretora do lugar, at\u00e9 que Carmem, irm\u00e3 de Jos\u00e9 Ricardo, entre em seu lugar. Chegam ainda mais \u00f3rf\u00e3os: Pata, Mosca, Binho e Rafa, que viviam nas ruas antes de entrarem na institui\u00e7\u00e3o. Pata e Mili tornam-se amigas rapidamente, enquanto Mosca, Binho e Rafa s\u00e3o os primeiros garotos a entrar no abrigo. As crian\u00e7as sem-teto foram ajudadas por uma doce e bela garota que tocam e mudam a vida delas, assim como as das garotas \u00f3rf\u00e3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo novela \u201cChiquititas\u201d 22\/06 : no cap\u00edtulo 464(*) da novela \u201cChiquititas\u201d, resumo de sexta-feira, 22 de junho, Vivi diz para Tati e Cris que encontrou com Cintia por acaso no shopping. Cris pergunta o motivo dela estar num site com Cintia. Vivi responde que n\u00e3o perderia a chance de aparecer na m\u00eddia. Tati diz que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49690,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[409,379,372,343],"tags":[441],"class_list":{"0":"post-144527","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-chiquititas","8":"category-novelas","9":"category-sbt","10":"category-televisao","11":"tag-resumo-do-dia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144527"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/49690"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}