{"id":144547,"date":"2018-06-22T00:05:48","date_gmt":"2018-06-22T03:05:48","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=144547"},"modified":"2018-06-21T18:25:55","modified_gmt":"2018-06-21T21:25:55","slug":"setor-varejista-tem-alta-de-empregos-em-sao-paulo","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/setor-varejista-tem-alta-de-empregos-em-sao-paulo\/144547","title":{"rendered":"Setor varejista tem alta de empregos em S\u00e3o Paulo"},"content":{"rendered":"<p> O mercado de trabalho no setor varejista, em S\u00e3o Paulo, voltou a criar <strong><em>novos empregos<\/em><\/strong> ap\u00f3s tr\u00eas meses de saldo negativo. Pesquisa mensal feita pela Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de S\u00e3o Paulo (Fecomercio), com base em dados do Minist\u00e9rio do Trabalho, mostrou saldo positivo na cria\u00e7\u00e3o de 2.340 novos empregos formais em abril, resultado de 77.179 admiss\u00f5es e 74.839 desligamentos.<\/p>\n<p>O setor varejista apresentou 2.063.079 v\u00ednculos empregat\u00edcios, um crescimento de 0,4% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2017. No acumulado de 12 meses, 8.995 empregos com carteira assinada foram gerados, revertendo o cen\u00e1rio negativo observado nos dois anos anteriores.<\/p>\n<p> No comparativo anual, quatro das nove atividades analisadas registraram crescimento de empregados, com destaque para os segmentos de farm\u00e1cias e perfumarias e de eletrodom\u00e9sticos, eletr\u00f4nicos e lojas de departamentos (ambos com eleva\u00e7\u00e3o de 2,9%); e de autope\u00e7as e acess\u00f3rios (1,1%). Setores como lojas de m\u00f3veis e decora\u00e7\u00e3o reduziram o n\u00famero de empregados e -1,5%) e as lojas de vestu\u00e1rio, tecidos e cal\u00e7ados -0,9%.<\/p>\n<p>A assessoria econ\u00f4mica da Fecomercio indica que, tradicionalmente, o varejo registra mais desligamentos do que admiss\u00f5es no in\u00edcio de cada ano, e, em 2018, esse cen\u00e1rio n\u00e3o foi diferente. Vale ressaltar, por\u00e9m, que as 26.130 vagas encerradas no primeiro quadrimestre representam o menor saldo negativo para o per\u00edodo desde 2013.<\/p>\n<p>A entidade aponta um cen\u00e1rio turbulento para o m\u00eas de maio, levando em considera\u00e7\u00e3o o Dia das M\u00e3es, considerada a segunda data mais importante para o setor, e os efeitos da greve dos caminhoneiros.<\/p>\n<p> O varejo paulistano criou 757 empregos com carteira assinada em abril, resultado de 24.065 admiss\u00f5es contra 23.308 desligamentos. No acumulado de 12 meses, foram gerados 2.238 postos de trabalho formais. O com\u00e9rcio paulistano encerrou o m\u00eas com um total de 645.573 trabalhadores ativos, alta de 0,3% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado.<\/p>\n<p>A pesquisa de emprego analisa o desempenho do mercado de trabalho formal em 16 regi\u00f5es do estado e nove atividades do varejo. As informa\u00e7\u00f5es s\u00e3o do Minist\u00e9rio do Trabalho, com base no Cadastro Geral de Empregados e Desempregados (Caged).<\/p>\n<p>Da Ag\u00eancia Brasil<br \/>\nEdi\u00e7\u00e3o: Maria Claudia<br \/>\n22\/06\/2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mercado de trabalho no setor varejista, em S\u00e3o Paulo, voltou a criar novos empregos ap\u00f3s tr\u00eas meses de saldo negativo. Pesquisa mensal feita pela Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de S\u00e3o Paulo (Fecomercio), com base em dados do Minist\u00e9rio do Trabalho, mostrou saldo positivo na cria\u00e7\u00e3o de 2.340 novos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,7],"tags":[441],"class_list":{"0":"post-144547","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia","9":"tag-resumo-do-dia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=144547"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/144547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/57585"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=144547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=144547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=144547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}