{"id":158321,"date":"2018-11-11T16:03:40","date_gmt":"2018-11-11T18:03:40","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=158321"},"modified":"2018-11-11T16:03:40","modified_gmt":"2018-11-11T18:03:40","slug":"previsao-do-tempo-na-regiao-norte-12-11-e-13-11","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/previsao-do-tempo-na-regiao-norte-12-11-e-13-11\/158321","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Norte 12\/11 e 13\/11"},"content":{"rendered":"<p><strong><em> Previs\u00e3o do tempo<\/em><\/strong> na Regi\u00e3o <em><strong>Norte<\/strong><\/em>, segundo o CPTEC\/INPE, em 12\/11\/2018: No norte do PA, no AP e norte de RR haver\u00e1 nebulosidade vari\u00e1vel com pancadas de chuva a partir da tarde. No noroeste e nordeste do PA e no nordeste do AM o sol aparecer\u00e1 entre poucas nuvens. Nas demais \u00e1rea da regi\u00e3o haver\u00e1 nebulosidade com pancadas de chuva isoladas. Temperatura est\u00e1vel. <\/p>\n<p>Tend\u00eancia: No norte do PA, no AP e norte de RR haver\u00e1 nebulosidade vari\u00e1vel com pancadas de chuva a partir da tarde. No noroeste e nordeste do PA e no nordeste do AM o sol aparecer\u00e1 entre poucas nuvens. Nas demais \u00e1rea da regi\u00e3o haver\u00e1 nebulosidade com pancadas de chuva isoladas. Temperatura est\u00e1vel.<\/p>\n<p>Previs\u00e3o do tempo CPTEC\/INPE\/MCTI<\/p>\n<p>&#8212;<\/p>\n<p>O CPTEC (Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos) do INPE (Instituto Nacional de Pesquisas Espaciais) \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Com o novo supercomputador (CRAY XT6), rec\u00e9m adquirido, ser\u00e1 poss\u00edvel ao Centro melhorar a resolu\u00e7\u00e3o espacial dos modelos de previs\u00e3o de tempo, de clima sazonal, ambiental (qualidade do ar) e de proje\u00e7\u00f5es de cen\u00e1rios de mudan\u00e7as clim\u00e1ticas. O CPTEC j\u00e1 vem aperfei\u00e7oando seus modelos para que o novo supercomputador tamb\u00e9m possa gerar previs\u00f5es com mais dias de anteced\u00eancia, al\u00e9m de prever chuvas e eventos extremos com maior confiabilidade.<\/p>\n<p>O cluster UNA com 1100 processadores tem capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Tudo isso, significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Norte, segundo o CPTEC\/INPE, em 12\/11\/2018: No norte do PA, no AP e norte de RR haver\u00e1 nebulosidade vari\u00e1vel com pancadas de chuva a partir da tarde. No noroeste e nordeste do PA e no nordeste do AM o sol aparecer\u00e1 entre poucas nuvens. Nas demais \u00e1rea da regi\u00e3o haver\u00e1 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":148084,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[327],"tags":[475],"class_list":{"0":"post-158321","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-clima","8":"tag-previsao-tempo"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/158321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=158321"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/158321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148084"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=158321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=158321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=158321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}