{"id":159981,"date":"2018-11-26T23:55:39","date_gmt":"2018-11-27T01:55:39","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=159981"},"modified":"2018-11-26T22:15:10","modified_gmt":"2018-11-27T00:15:10","slug":"brasil-assume-meta-para-reduzir-144-mil-toneladas-de-acucar-ate-2022","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/brasil-assume-meta-para-reduzir-144-mil-toneladas-de-acucar-ate-2022\/159981","title":{"rendered":"Brasil assume meta para reduzir 144 mil toneladas de a\u00e7\u00facar at\u00e9 2022"},"content":{"rendered":"<p> O Brasil quer reduzir 144 mil toneladas de a\u00e7\u00facar de bolos, misturas para bolos, produtos l\u00e1cteos, achocolatados, bebidas a\u00e7ucaradas e biscoitos recheados. O acordo foi\u00a0assinado pelo ministro da Sa\u00fade, Gilberto Occhi, e os presidentes de associa\u00e7\u00f5es do setor produtivo de alimentos. Ao estabelecer a meta at\u00e9 2022, o Brasil se destaca como um dos primeiros pa\u00edses do mundo a buscar a <strong><em>diminui\u00e7\u00e3o do a\u00e7\u00facar nos alimentos industrializados<\/em><\/strong>. O acordo segue o mesmo par\u00e2metro do feito para a redu\u00e7\u00e3o do s\u00f3dio, que foi capaz de retirar mais de 17 mil toneladas de s\u00f3dio dos alimentos processados em quatro anos.<\/p>\n<p>\u201cO acordo vai ajudar a melhorar a conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o na busca de alimentos mais saud\u00e1veis. O apoio da ind\u00fastria na redu\u00e7\u00e3o do a\u00e7\u00facar permitir\u00e1 que popula\u00e7\u00e3o busque uma vida mais saud\u00e1vel e tenha menos problemas de doen\u00e7as que possam ser evitadas. \u00c9 importante que n\u00f3s tenhamos avan\u00e7os dessa natureza\u201d, destacou o ministro da Sa\u00fade, Gilberto Occhi.<\/p>\n<p>O monitoramento da redu\u00e7\u00e3o ser\u00e1 feito a cada dois anos pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa), sendo a primeira an\u00e1lise no final de 2020. Fazem parte do acordo a Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias da Alimenta\u00e7\u00e3o (ABIA), a Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de Refrigerantes e de Bebidas N\u00e3o Alco\u00f3licas (ABIR), a Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de Biscoitos, Massas Aliment\u00edcias e P\u00e3es e Bolos Industrializados (ABIMAPI) e a Associa\u00e7\u00e3o Brasileira de Latic\u00ednios (Viva L\u00e1cteos).<\/p>\n<p>Para estabelecer as metas das cinco categorias de alimentos, o Minist\u00e9rio da Sa\u00fade analisou crit\u00e9rios que envolvem desde o consumo e distribui\u00e7\u00e3o dos teores de a\u00e7\u00facar dos alimentos at\u00e9 a necessidade de redu\u00e7\u00e3o dos n\u00edveis m\u00e1ximos do alimento; queda dos teores de a\u00e7\u00facares livres n\u00e3o resultantes em aumento no valor energ\u00e9tico e de adi\u00e7\u00e3o ou substitui\u00e7\u00e3o por ado\u00e7antes, al\u00e9m do percentual de produtos a serem reformulados para atingirem \u00e0 meta.<\/p>\n<p>Considerando os produtos com maior quantidade de a\u00e7\u00facar, os biscoitos e produtos l\u00e1cteos ter\u00e3o os maiores percentuais de meta para redu\u00e7\u00e3o do alimento, com a meta de retirar 62,4% e 53,9% de a\u00e7\u00facar da composi\u00e7\u00e3o, respectivamente. Para bolos, a meta \u00e9 de at\u00e9 32,4% e para as misturas para bolos, at\u00e9 46,1% do teor de a\u00e7\u00facar. J\u00e1 os achocolatados, tem a meta de cair at\u00e9 10,5% e as bebidas a\u00e7ucaradas at\u00e9 33,8%.<\/p>\n<p>\u201cN\u00f3s n\u00e3o temos a menor d\u00favida, que isso \u00e9 fundamental. Temos que controlar fortemente as doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis, principalmente hipertens\u00e3o e diabetes. Com isso, vamos contribuir para uma sa\u00fade melhor para os brasileiros\u201d, ressaltou o secret\u00e1rio de Aten\u00e7\u00e3o \u00e0 Sa\u00fade, Francisco Assis.<\/p>\n<p>Os brasileiros consomem 50% a mais de a\u00e7\u00facar do que o recomendado pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS). Isso significa que, por dia, cada brasileiro, consome em m\u00e9dia 18 colheres de ch\u00e1 do produto (o que corresponde a 80g de a\u00e7\u00facar\/dia), quando o recomendado seria at\u00e9 12. Desse total, 64% corresponde \u00e0 a\u00e7\u00facares adicionados, aquela colherzinha a mais que voc\u00ea coloca nos alimentos. O restante do consumo \u00e9 o a\u00e7\u00facar presente nos alimentos industrializados.<\/p>\n<p>O alto de a\u00e7\u00facar j\u00e1 impacta no aumento de doen\u00e7as cr\u00f4nicas n\u00e3o-transmiss\u00edveis. Na \u00faltima d\u00e9cada, o diabetes cresceu 54% nos homens e 28,5% nas mulheres. Outra doen\u00e7a que tem crescido entre os brasileiros, e que est\u00e1 relacionada com o alto consumo de a\u00e7\u00facar, \u00e9 a obesidade. A condi\u00e7\u00e3o cl\u00ednica subiu mais de 60%.<\/p>\n<p>MUDAN\u00c7A DE H\u00c1BITOS<br \/>\nO incentivo para uma alimenta\u00e7\u00e3o adequada e saud\u00e1vel e a pr\u00e1tica de atividades f\u00edsicas \u00e9 prioridade do Governo Federal.\u00a0Em 2017, o Minist\u00e9rio da Sa\u00fade adotou internacionalmente metas para frear o crescimento do excesso de peso e obesidade no pa\u00eds. O compromisso foi de deter o crescimento da obesidade na popula\u00e7\u00e3o adulta at\u00e9 2019; reduzir o consumo regular de refrigerante e suco artificial em pelo menos 30% na popula\u00e7\u00e3o adulta at\u00e9 2019 e ampliar no m\u00ednimo de 17,8% o percentual de adultos que consomem frutas e hortali\u00e7as regularmente at\u00e9 2019.<\/p>\n<p>Outra a\u00e7\u00e3o para a promo\u00e7\u00e3o da alimenta\u00e7\u00e3o saud\u00e1vel \u00e9 a publica\u00e7\u00e3o do Guia Alimentar para a Popula\u00e7\u00e3o Brasileira. Reconhecida mundialmente pela sua abordagem integral, a publica\u00e7\u00e3o orienta a popula\u00e7\u00e3o com recomenda\u00e7\u00f5es sobre alimenta\u00e7\u00e3o saud\u00e1vel baseada principalmente no consumo de alimentos in natura ou minimamente processados.<\/p>\n<p>Por Victor Maciel, da Ag\u00eancia Sa\u00fade<br \/>\nhttp:\/\/portalms.saude.gov.br\/noticias\/agencia-saude\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil quer reduzir 144 mil toneladas de a\u00e7\u00facar de bolos, misturas para bolos, produtos l\u00e1cteos, achocolatados, bebidas a\u00e7ucaradas e biscoitos recheados. O acordo foi\u00a0assinado pelo ministro da Sa\u00fade, Gilberto Occhi, e os presidentes de associa\u00e7\u00f5es do setor produtivo de alimentos. Ao estabelecer a meta at\u00e9 2022, o Brasil se destaca como um dos primeiros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":148277,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,5],"tags":[],"class_list":{"0":"post-159981","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-saude-e-vida"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/159981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=159981"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/159981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148277"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=159981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=159981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=159981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}