{"id":160064,"date":"2018-11-27T23:53:31","date_gmt":"2018-11-28T01:53:31","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=160064"},"modified":"2018-11-27T20:14:41","modified_gmt":"2018-11-27T22:14:41","slug":"pos-graduacao-em-estatistica-na-ufscar-e-usp-esta-com-inscricoes-abertas","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/pos-graduacao-em-estatistica-na-ufscar-e-usp-esta-com-inscricoes-abertas\/160064","title":{"rendered":"P\u00f3s-Gradua\u00e7\u00e3o em Estat\u00edstica na UFSCar e USP est\u00e1 com inscri\u00e7\u00f5es abertas"},"content":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O Programa Interinstitucional de <strong><em>P\u00f3s-Gradua\u00e7\u00e3o em Estat\u00edstica<\/em><\/strong> (PIPGEs) est\u00e1 com inscri\u00e7\u00f5es abertas at\u00e9 29 de novembro de 2018 para o processo seletivo nos cursos de mestrado e doutorado, que come\u00e7am no in\u00edcio de 2019. o Programa \u00e9 uma parceria da Universidade Federal de S\u00e3o Carlos (UFSCar) com o Instituto de Ci\u00eancias Matem\u00e1ticas e de Computa\u00e7\u00e3o (ICMC) da USP, ambos sediados em S\u00e3o Carlos.<\/p>\n<p>O principal objetivo do PIPGEs \u00e9 a forma\u00e7\u00e3o de pesquisadores com atua\u00e7\u00e3o direta na modelagem, descri\u00e7\u00e3o e estima\u00e7\u00e3o de fen\u00f4menos aleat\u00f3rios, assim como na sua aplica\u00e7\u00e3o na ind\u00fastria e em \u00e1reas como Medicina e Biologia. As linhas de pesquisa s\u00e3o: An\u00e1lise de Sobreviv\u00eancia, Infer\u00eancia Bayesiana, Infer\u00eancia Estat\u00edstica, Modelos de Regress\u00e3o e Probabilidade.<\/p>\n<p>S\u00e3o oferecidas 30 vagas para o mestrado e 20 para o doutorado. Para o mestrado, al\u00e9m da an\u00e1lise da forma\u00e7\u00e3o acad\u00eamica e do curr\u00edculo, far\u00e1 parte dos crit\u00e9rios de sele\u00e7\u00e3o o desempenho no curso de Teoria das Probabilidades no Programa de Ver\u00e3o do PIPGEs, que acontece a partir do dia 2 de janeiro de 2019. Os processos seletivos do doutorado e doutorado direto consistir\u00e3o de an\u00e1lise da forma\u00e7\u00e3o acad\u00eamica e do Curr\u00edculo Lattes, al\u00e9m do tempo de titula\u00e7\u00e3o do mestrado para as vagas de doutorado.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser feitas pelo\u00a0. A divulga\u00e7\u00e3o do resultado final do processo seletivo de mestrado ser\u00e1 no dia 19 de fevereiro de 2019 e de doutorado em 21 de dezembro de 2018.<\/p>\n<p>Mais informa\u00e7\u00f5es:\u00a0.<\/p>\n<p> http:\/\/agencia.fapesp.br\/noticias\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O Programa Interinstitucional de P\u00f3s-Gradua\u00e7\u00e3o em Estat\u00edstica (PIPGEs) est\u00e1 com inscri\u00e7\u00f5es abertas at\u00e9 29 de novembro de 2018 para o processo seletivo nos cursos de mestrado e doutorado, que come\u00e7am no in\u00edcio de 2019. o Programa \u00e9 uma parceria da Universidade Federal de S\u00e3o Carlos (UFSCar) com o Instituto de Ci\u00eancias Matem\u00e1ticas e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":148076,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[351,370],"tags":[],"class_list":{"0":"post-160064","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cursos","8":"category-inscricao"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/160064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=160064"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/160064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148076"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=160064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=160064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=160064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}