{"id":160352,"date":"2018-11-29T23:59:03","date_gmt":"2018-11-30T01:59:03","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=160352"},"modified":"2018-11-29T16:54:25","modified_gmt":"2018-11-29T18:54:25","slug":"ans-apresenta-a-senadores-proposta-de-reajuste-para-planos-de-saude","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2018\/ans-apresenta-a-senadores-proposta-de-reajuste-para-planos-de-saude\/160352","title":{"rendered":"ANS apresenta a senadores proposta de reajuste para planos de sa\u00fade"},"content":{"rendered":"<p> Representantes da Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) apresentaram, na Comiss\u00e3o de Assuntos Sociais do Senado, os c\u00e1lculos para reajustar os <strong><em>planos de sa\u00fade<\/em><\/strong>. Segundo eles, a f\u00f3rmula foi discutida com \u00f3rg\u00e3os de defesa do consumidor, Minist\u00e9rio P\u00fablico e organiza\u00e7\u00f5es ligadas \u00e0 sa\u00fade.<\/p>\n<p>A audi\u00eancia foi acompanhada pelo diretor de Normas e Habilita\u00e7\u00e3o dos Produtos da ANS, Rog\u00e9rio Scarabel.<\/p>\n<p>Ap\u00f3s a avalia\u00e7\u00e3o, ANS informou que ir\u00e1 publicar uma nota normativa sobre os reajustes, que valer\u00e1 a partir de maio de 2019. Se aprovada, a nova f\u00f3rmula para reajuste dos planos levar\u00e1 em conta o \u00edndice do valor das despesas assistenciais (IVDA), que \u00e9 formado por tr\u00eas elementos.<\/p>\n<p>Os tr\u00eas elementos s\u00e3o a varia\u00e7\u00e3o dos pre\u00e7os da despesa assistencial (VDA) considerados os gastos da carteira de planos individuais das operadoras. O segundo \u00e9 o desconto da varia\u00e7\u00e3o da Receita Faixa Et\u00e1ria (VFE), proveniente dos reajustes previstos toda vez em que o usu\u00e1rio muda de faixa et\u00e1ria. Desse valor tira-se 1.<\/p>\n<p>O terceiro aspecto o fator denominado \u201cganhos de efici\u00eancia\u201d (FGE). Isso porque a ANS pretende estimular as operadoras a atuarem como gestoras de assist\u00eancia \u00e0 sa\u00fade, estimulando a efici\u00eancia e evitando um modelo que transforme a operadora numa mera repassadora de custos assistenciais.<\/p>\n<p>Atingido o \u00edndice de varia\u00e7\u00e3o da despesa assistencial (IVDA = VDA\/VFE-1-FGE), o percentual de reajuste \u00e9 igual a 80% x IVDA + 20% x IPCA Expurgado (o que \u00e9 eliminado do \u00edndice nacional de pre\u00e7os ao consumidor amplo s\u00e3o as contas referentes aos planos de sa\u00fade e \u00e0s despesas m\u00e9dicas).<\/p>\n<p>An\u00e1lises<br \/>\nO coordenador da \u00e1rea que elaborou a f\u00f3rmula de reajuste, Bruno Morestrello, afirmou que o que se faz \u201cno expurgo \u00e9 evitar que o reajuste do ano seguinte seja retroalimentado pelo reajuste do ano anterior\u201d. Segundo ele, n\u00e3o \u00e9 poss\u00edvel estimar um reajuste apenas com base na infla\u00e7\u00e3o do per\u00edodo.<\/p>\n<p>\u201cAl\u00e9m de a \u00e1rea de sa\u00fade ter um comportamento de pre\u00e7os diferente da m\u00e9dia da economia, existe o efeito da frequ\u00eancia do uso dos servi\u00e7os, a varia\u00e7\u00e3o de eventos como consultas, exames, cirurgias\u201d, afirmou o especialista.<\/p>\n<p>Para os representantes da ANS, a nova f\u00f3rmula de c\u00e1lculo dos planos de sa\u00fade \u00e9 vantajosa porque os dados que comp\u00f5em o reajuste s\u00e3o p\u00fablicos e audit\u00e1veis. Os t\u00e9cnicos da ag\u00eancia tamb\u00e9m apontam como benef\u00edcio o fato de os dados serem retirados do pr\u00f3prio mercado de planos individuais e terem menor defasagem entre o per\u00edodo de c\u00e1lculo e a aplica\u00e7\u00e3o do reajuste. Apontam ainda a corre\u00e7\u00e3o das despesas n\u00e3o-assistenciais ser\u00e1 feita por \u00edndice espec\u00edfico, expurgando as despesas assistenciais.<\/p>\n<p>Considera\u00e7\u00f5es<br \/>\nO coordenador da \u00e1rea que elaborou a f\u00f3rmula de reajuste, Bruno Morestrello, disse que o novo c\u00e1lculo inclui as despesas assistenciais e n\u00e3o assistenciais. Segundo ele, aproximadamente 80% dos gastos de um plano de sa\u00fade s\u00e3o procedimentos, terapias, interna\u00e7\u00f5es e exames \u2014 as despesas assistenciais.<\/p>\n<p>Ainda de acordo com suas estimativas, Morestrello disse que os demais 20% s\u00e3o despesas n\u00e3o-assistenciais, ou seja, o que a operadora do plano de sa\u00fade gasta com pessoal, locomo\u00e7\u00e3o e manuten\u00e7\u00e3o, por exemplo.<\/p>\n<p>29\/11\/2018<br \/>\nAg\u00eancia Brasil<br \/>\nEdi\u00e7\u00e3o: Val\u00e9ria Aguiar<br \/>\nhttp:\/\/agenciabrasil.ebc.com.br\/ultimas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes da Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) apresentaram, na Comiss\u00e3o de Assuntos Sociais do Senado, os c\u00e1lculos para reajustar os planos de sa\u00fade. Segundo eles, a f\u00f3rmula foi discutida com \u00f3rg\u00e3os de defesa do consumidor, Minist\u00e9rio P\u00fablico e organiza\u00e7\u00f5es ligadas \u00e0 sa\u00fade. A audi\u00eancia foi acompanhada pelo diretor de Normas e Habilita\u00e7\u00e3o dos Produtos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":148074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,7],"tags":[],"class_list":{"0":"post-160352","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/160352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=160352"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/160352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148074"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=160352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=160352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=160352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}