{"id":175070,"date":"2019-04-23T14:57:01","date_gmt":"2019-04-23T17:57:01","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=175070"},"modified":"2019-05-09T19:08:09","modified_gmt":"2019-05-09T22:08:09","slug":"resumo-novela-a-dona-24-04-jose-miguel-informa-valentina-que-sua-fazenda-nao-esta-a-venda","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2019\/resumo-novela-a-dona-24-04-jose-miguel-informa-valentina-que-sua-fazenda-nao-esta-a-venda\/175070","title":{"rendered":"Resumo novela \u201cA Dona\u201d 24\/04: Jos\u00e9 Miguel informa Valentina que sua fazenda n\u00e3o est\u00e1 \u00e0 venda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-173633\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/a-dona-270x300.jpg\" alt=\"\" width=\"270\" height=\"300\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/a-dona-270x300.jpg 270w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/a-dona-168x187.jpg 168w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/a-dona.jpg 380w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/>Resumo da novela <strong><em>\u201cA Dona&#8221;<\/em><\/strong> em 24\/04: no cap\u00edtulo 018(*) da novela, quarta-feira, 24 de abril, Valentina, furiosa, pergunta a Rodrigo o porqu\u00ea de ter ateado fogo na cabana de Jo\u00e3o e Teresa. Ele responde que s\u00f3 quis se assegurar que as ordens da dona fossem cumpridas. Valentina diz que jamais ordenaria tamanha selvageria. Ela ordena que paguem os direitos de Jo\u00e3o. Valentina descobre que est\u00e3o atirando em seu gado por eles estarem indo beber \u00e1gua na fazenda Montesinos. Ela jura que se algum animal morrer eles ver\u00e3o do que ela \u00e9 capaz. Valentina diz a Sabino que diga a seus patr\u00f5es que a vendam a fazenda Montesinos. Dessa forma, evitariam esses problemas com os animais que passam de uma fazenda a outra.<\/p>\n<p>Jos\u00e9 Miguel diz a Valentina que sua fazenda n\u00e3o est\u00e1 \u00e0 venda. Valentina se zanga e diz a Jos\u00e9 Miguel que eles s\u00f3 voltar\u00e3o a se ver caso ele aceite a oferta de compra da Montesinos. Valentina cobra Ernesto pelo detetive contratado ainda n\u00e3o ter tido not\u00edcias de Alonso. Furiosa, ela ordena que Ernesto demita o detetive e contrate outro, sem se importar com valores, pois sua prioridade \u00e9 mandar Alonso para a cadeia. Rodrigo, furioso, amea\u00e7a Sabino por ter disparado contra os animais de Valentina. Sabino responde que nunca feriu nenhum, e que s\u00f3 dispara para assust\u00e1-los. Sabino diz que Rodrigo n\u00e3o \u00e9 um homem honrado, pois enriqueceu as custas de roubos contra Valentina.<\/p>\n<p>Rodrigo se enfurece com a acusa\u00e7\u00e3o e amea\u00e7a bater em Sabino. Neste momento, Jos\u00e9 Miguel chega e adverte Rodrigo que, caso ele toque em Sabino, pagar\u00e1 caro. Teresa agradece ao ato nobre de Valentina em abrigar a ela e seus filhos. Jesus se aproxima dela e diz que ela \u00e9 muito linda e boa. Jesus beija Valentina. Sandra invade a casa de Valentina e a esbofeteia, acusando a de andar as escondidas com seu noivo. Valentina devolve a bofetada e diz que n\u00e3o anda com ningu\u00e9m pelo povoado. Valentina conclui que Ivana \u00e9 a mulher que anda passeando com homens pelo povoado, vai at\u00e9 o quarto da prima, joga as roupas de Ivana no ch\u00e3o e ordena que ela deixe sua fazenda imediatamente.<\/p>\n<p>(*) edi\u00e7\u00e3o do SBT, Novela \u201cA Dona\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Destaques<\/p>\n<p>&#8220;A Dona&#8221; &#8211; Valentina Vila\u00e7a (Lucero) \u00e9 uma mulher que tem uma grande fortuna, que seus pais deixaram para ela quando morreram em um acidente de carro. Ela tem uma mans\u00e3o na Cidade do M\u00e9xico, onde vive com sua tia Isabel Rangel de Dorantes (Silvia Pinal), e sua prima Ivana Dorantes Rangel (Gabriela Spanic) que trata Valentina com muita indiferen\u00e7a e sente inveja dela.<\/p>\n<p>Tudo muda para Valentina quando seu noivo Alonso Penalva (David Zepeda), tramando com Ivana no dia de seu casamento, a deixa esperando no altar. A partir da\u00ed, Valentina se torna uma mulher amarga, e vai para sua fazenda, no interior. Chegando l\u00e1, ela conhece seu vizinho Jos\u00e9 Miguel Montesinos (Fernando Colunga).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela \u201cA Dona&#8221; em 24\/04: no cap\u00edtulo 018(*) da novela, quarta-feira, 24 de abril, Valentina, furiosa, pergunta a Rodrigo o porqu\u00ea de ter ateado fogo na cabana de Jo\u00e3o e Teresa. Ele responde que s\u00f3 quis se assegurar que as ordens da dona fossem cumpridas. Valentina diz que jamais ordenaria tamanha selvageria. Ela [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":173626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[379,372,343],"tags":[441],"class_list":{"0":"post-175070","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-sbt","9":"category-televisao","10":"tag-resumo-do-dia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/175070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=175070"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/175070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/173626"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=175070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=175070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=175070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}