{"id":175319,"date":"2019-04-27T18:24:32","date_gmt":"2019-04-27T21:24:32","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=175319"},"modified":"2019-04-27T16:17:30","modified_gmt":"2019-04-27T19:17:30","slug":"resumo-novela-orfaos-da-terra-29-04-aziz-e-fauze-chegam-ao-brasil","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2019\/resumo-novela-orfaos-da-terra-29-04-aziz-e-fauze-chegam-ao-brasil\/175319","title":{"rendered":"Resumo novela \u201c\u00d3rf\u00e3os da Terra\u201d 29\/04: Aziz e Fauze chegam ao Brasil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-173643\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/orfaos-da-terra-01-376x300.jpg\" alt=\"\" width=\"376\" height=\"300\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/orfaos-da-terra-01-376x300.jpg 376w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/orfaos-da-terra-01-234x187.jpg 234w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/orfaos-da-terra-01-560x447.jpg 560w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/orfaos-da-terra-01.jpg 600w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/p>\n<p>Resumo da novela <strong><em>\u201c\u00d3rf\u00e3os da Terra&#8221;<\/em><\/strong> em 29\/04: no cap\u00edtulo 024(*) da novela, segunda-feira, 29 de abril, Aziz se descontrola ao saber da gravidez de Laila. Dalila humilha Youssef. Val\u00e9ria conhece Laila e Jamil, e deduz que Bruno se afastou por conta da mo\u00e7a. Dalila incentiva Aziz a viajar para o Brasil, e amea\u00e7a \u00c1ida. Zuleika e Almeidinha combinam um novo encontro. Helena procura Elias. Aziz vai em busca de Laila e Jamil. Dalila expulsa \u00c1ida de sua casa.<\/p>\n<p>Rog\u00e9rio comunica a Padre Zoran que seu recurso contra a ordem de despejo foi negado, e o sacerdote desabafa com Missade. Bruno convida Teresa para acompanh\u00e1-lo ao casamento de Laila. Hussein se recupera e jura a Samira que vingar\u00e1 a morte de Soraia. Rania, Cibele e Miguel descobrem que Zuleika est\u00e1 se encontrando com Almeidinha.  Chega o dia do casamento de Laila e Jamil. Aziz e Fauze chegam ao Brasil.<\/p>\n<p>(*) edi\u00e7\u00e3o Globo, Novela \u201c\u00d3rf\u00e3os da Terra\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Destaques<\/p>\n<p>Novela \u201c\u00d3rf\u00e3os da Terra\u201d &#8211; A hist\u00f3ria se inicia na S\u00edria, onde Missade (Ana Cec\u00edlia Costa) e Elias (Marco Ricca) vivem com seus filhos Laila (Julia Dalavia) e Khaled (Rodrigo Vidal) at\u00e9 serem v\u00edtimas da guerra e terem que se refugiar no L\u00edbano. Com o irm\u00e3o gravemente ferido e a fam\u00edlia presa num campo de concentra\u00e7\u00e3o, Laila aceita se casar com o sheik Aziz (Herson Capri) \u2013 um homem cruel e muito mais velho \u2013 em troca de dinheiro para pagar o tratamento m\u00e9dico.<\/p>\n<p>Por\u00e9m, o menino falece e a mo\u00e7a decide fugir para o Brasil com seus pais na noite de n\u00fapcias, antes do casamento ser consumado, indo morar com seus tios, R\u00e2nia (Eliane Giardini) e Miguel (Paulo Betti). Irritado, o sheik manda Jammil (Renato G\u00f3es), seu bra\u00e7o-direito e noivo de sua filha, Dalila (Alice Wegmann), buscar a mo\u00e7a e traz\u00ea-la a for\u00e7a, por\u00e9m os dois acabam se apaixonando e se tornam fugitivos da fam\u00edlia Abdallah.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela \u201c\u00d3rf\u00e3os da Terra&#8221; em 29\/04: no cap\u00edtulo 024(*) da novela, segunda-feira, 29 de abril, Aziz se descontrola ao saber da gravidez de Laila. Dalila humilha Youssef. Val\u00e9ria conhece Laila e Jamil, e deduz que Bruno se afastou por conta da mo\u00e7a. Dalila incentiva Aziz a viajar para o Brasil, e amea\u00e7a \u00c1ida. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":173640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[379,540,375,343],"tags":[441],"class_list":{"0":"post-175319","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-orfaos-da-terra","9":"category-rede-globo","10":"category-televisao","11":"tag-resumo-do-dia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/175319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=175319"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/175319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/173640"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=175319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=175319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=175319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}