{"id":34700,"date":"2011-04-19T21:51:10","date_gmt":"2011-04-20T01:51:10","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34700"},"modified":"2011-04-19T21:51:10","modified_gmt":"2011-04-20T01:51:10","slug":"paixao-de-cristo-de-piracicaba-segue-ate-domingo","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/paixao-de-cristo-de-piracicaba-segue-ate-domingo\/34700","title":{"rendered":"Paix\u00e3o de Cristo de Piracicaba segue at\u00e9 domingo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34702\" title=\"paixao cristo semana santa\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/paixao-cristo-semana-santa1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/paixao-cristo-semana-santa1.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/paixao-cristo-semana-santa1-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/paixao-cristo-semana-santa1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Apesar de seus 22 anos de apresenta\u00e7\u00f5es ininterruptas, a f\u00f3rmula n\u00e3o se  esgota. Mais uma vez a Associa\u00e7\u00e3o Cultural e Teatral Guarant\u00e3 emociona o p\u00fablico  com um espet\u00e1culo novo, renovado e com um final surpreendente. Estes s\u00e3o  atributos da <em><strong>Paix\u00e3o de Cristo<\/strong><\/em> de 2011, que estreou no \u00faltimo domingo (17) e  segue por toda a <em><strong>Semana Santa<\/strong><\/em>, com mais seis apresenta\u00e7\u00f5es, sempre \u00e0s 20 horas,  no Engenho Central.<\/p>\n<p>A 22\u00aa edi\u00e7\u00e3o de uma das maiores montagens teatrais do pa\u00eds traz tamb\u00e9m  novidades na encena\u00e7\u00e3o, com duas cenas novas: os milagres da mulher enferma e do  menino endemoniado. \u201cAchei lindo o destaque dado para as crian\u00e7as. A ora\u00e7\u00e3o do  Pai Nosso, com Jesus pr\u00f3ximo \u00e0 arquibancada e voltado ao p\u00fablico, foi muito  emocionante. Assim como o final junto \u00e0 plat\u00e9ia. Maravilhoso!\u201d, exclamou  Carolina Penatti, de Santa B\u00e1rbara d\u2019Oeste.<\/p>\n<p>Com cerca de duas horas de dura\u00e7\u00e3o e com a participa\u00e7\u00e3o de mais de 400  pessoas no elenco, entre atores e figurantes, todos volunt\u00e1rios, a montagem tem  dire\u00e7\u00e3o de Jo\u00e3o Scarpa, cen\u00e1rio assinado por Cyro Del Nero (in memoriam),  figurinos de Carlos ABC e texto\/ narra\u00e7\u00e3o de Raul Rozados. \u201cAssim como nas  edi\u00e7\u00f5es anteriores, o p\u00fablico est\u00e1 respondendo muito bem ao espet\u00e1culo deste  ano\u201d, diz satisfeita Rosangela Pereira, presidente do Guarant\u00e3.<\/p>\n<p>O espet\u00e1culo<\/p>\n<p>Toda a pe\u00e7a transcorre em cenas simult\u00e2neas, num espa\u00e7o de oito mil metros  quadrados, projetado para permitir uma completa visibilidade das mais de 42  cenas, tudo a c\u00e9u aberto. S\u00e3o v\u00e1rios palcos que comp\u00f5em toda a estrutura,  lembrando uma verdadeira cidade cenogr\u00e1fica.<\/p>\n<p>A dramaticidade da trilha sonora, juntamente com recursos como carruagens,  bigas, soldados, artistas circenses e outros, remete o espectador \u00e0 \u00e9poca. No  decorrer da apresenta\u00e7\u00e3o, o p\u00fablico sente-se envolvido pelo clima do espet\u00e1culo,  num realismo obtido gra\u00e7as aos in\u00fameros efeitos c\u00eanicos e t\u00e9cnicos.<\/p>\n<p>Ingressos<\/p>\n<p>O valor dos ingressos para as arquibancadas \u00e9 de R$ 5 nos dias 17, 18, 19, 20  e 24 de abril (pre\u00e7o promocional). Para os dias 21, 22 e 23 de abril, os  ingressos custam R$ 10 (inteira). Idosos acima de 60 anos e estudantes t\u00eam 50%  de desconto, com a obrigatoriedade de apresenta\u00e7\u00e3o de documento comprobat\u00f3rio.  Crian\u00e7as at\u00e9 6 anos n\u00e3o pagam.<\/p>\n<p>O estacionamento custa R$10. O acesso ao Engenho Central pode ser feito pela  Ponte do Mirante ou pela Ponte P\u00eansil.<\/p>\n<p>Camarotes<\/p>\n<p>Para os camarotes, com cadeiras individuais, os valores s\u00e3o de R$ 25 por  pessoa e R$ 200 o pacote com 10 lugares, entre os dias 17 a 20 e 24 de abril.  Para os dias 21, 22 e 23 de abril, os valores passam para R$ 35 individual e R$  300 o pacote com 10 lugares.<\/p>\n<p>Outra boa not\u00edcia \u00e9 que os camarotes ter\u00e3o o sabor e o aroma do Caf\u00e9 Morro  Grande, preparado na medida certa para as noites da Semana Santa. \u201cA parceria  com a Associa\u00e7\u00e3o Guarant\u00e3 \u00e9 uma grande honra, pois valorizamos os eventos de  Piracicaba e apoiamos principalmente os que enaltecem a cultura local ou de  cunho social\u201d, diz Lia Lima Gatti H\u00f6fling, diretora de Marketing do Caf\u00e9 Morro  Grande.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>No local haver\u00e1 pra\u00e7a de alimenta\u00e7\u00e3o, equipe de seguran\u00e7a, estacionamento e  servi\u00e7o m\u00e9dico de emerg\u00eancia. Piracicaba est\u00e1 localizada a 160 quil\u00f4metros da  capital do Estado, a 80 km de Campinas e a 30 km de Americana, Limeira, Rio  Claro, Santa B\u00e1rbara d\u2019Oeste e Tiet\u00ea. No sentido S\u00e3o Paulo \u2013 interior, pela via  Anhanguera, acesse a Rodovia Luiz de Queiroz (SP 304) no km 120. Pela Rodovia  dos Bandeirantes, o acesso est\u00e1 no km 134 B.<\/p>\n<p>Informa\u00e7\u00f5es pelo fone (19) 3413-7888, pelo site www.guaranta.org.br ou pelos  e-mails guaranta@guaranta.org.br e <a href=\"mailto:paixaodecristo@guaranta.org.br\" target=\"_blank\">paixaodecristo@guaranta.org.br<\/a>.<\/p>\n<p>A realiza\u00e7\u00e3o \u00e9 da Associa\u00e7\u00e3o Cultural e Teatral Guarant\u00e3 e da Prefeitura  Municipal de Piracicaba, por meio da Secretaria de A\u00e7\u00e3o Cultural, e Lei de  Incentivo a Cultura, do Minist\u00e9rio da Cultura.<\/p>\n<p>Patroc\u00ednio M\u00e1ster Arcelor Mittal e Caterpillar Brasil. Patroc\u00ednio Bom Peixe.  Co-patroc\u00ednio Banco Santander, General Chains do Brasil e Ind\u00fastrias Marrucci.  Apoio cultural Ananda e Elring Klinger. Promo\u00e7\u00e3o cultural Jornal de  Piracicaba.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar de seus 22 anos de apresenta\u00e7\u00f5es ininterruptas, a f\u00f3rmula n\u00e3o se esgota. Mais uma vez a Associa\u00e7\u00e3o Cultural e Teatral Guarant\u00e3 emociona o p\u00fablico com um espet\u00e1culo novo, renovado e com um final surpreendente. Estes s\u00e3o atributos da Paix\u00e3o de Cristo de 2011, que estreou no \u00faltimo domingo (17) e segue por toda a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22],"tags":[],"class_list":{"0":"post-34700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34700"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34702"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}