{"id":34748,"date":"2011-04-24T20:01:26","date_gmt":"2011-04-25T00:01:26","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34748"},"modified":"2011-04-24T23:11:55","modified_gmt":"2011-04-25T03:11:55","slug":"institutos-federais-estao-autorizados-a-contratar-professores-e-tecnicos","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/institutos-federais-estao-autorizados-a-contratar-professores-e-tecnicos\/34748","title":{"rendered":"Institutos federais est\u00e3o autorizados a contratar professores e t\u00e9cnicos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34749\" title=\"professor\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/professor1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/professor1.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/professor1-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/professor1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Os institutos federais de educa\u00e7\u00e3o, ci\u00eancia e tecnologia est\u00e3o autorizados a <em><strong>contratar docentes e t\u00e9cnicos <\/strong><\/em>administrativos para as <em><strong>escolas federais<\/strong><\/em> de educa\u00e7\u00e3o profissional em funcionamento no pa\u00eds. Portaria interministerial dos Minist\u00e9rios da Educa\u00e7\u00e3o e do Planejamento, Or\u00e7amento e Gest\u00e3o (MPOG), est\u00e1 publicada no Di\u00e1rio Oficial da Uni\u00e3o da segunda-feira, 25, altera anexos dos decretos do banco de professor-equivalente e do quadro de refer\u00eancia dos t\u00e9cnicos administrativos dos institutos federais. Na pr\u00e1tica, a medida amplia o banco e o quadro de refer\u00eancia, permitindo que as institui\u00e7\u00f5es contratem, via concurso p\u00fablico, pelo menos 2.800 professores e 1.800 t\u00e9cnicos administrativos.<\/p>\n<p>Aqueles institutos que possuam concurso v\u00e1lido poder\u00e3o convocar e nomear o candidato aprovado de imediato.<\/p>\n<p>O banco de professor-equivalente e o quadro de refer\u00eancia de educa\u00e7\u00e3o b\u00e1sica, t\u00e9cnica e tecnol\u00f3gica dos institutos federais de educa\u00e7\u00e3o, ci\u00eancia e tecnologia foram criados por decretos em setembro de 2010. No entanto, o quantitativo de vagas previsto estava desatualizado em rela\u00e7\u00e3o \u00e0s novas escolas da rede federal.<\/p>\n<p>Hist\u00f3rico &#8211; Antes da exist\u00eancia do banco e do quadro de refer\u00eancia, as institui\u00e7\u00f5es necessitavam pedir autoriza\u00e7\u00e3o do MPOG cada vez que servidores se aposentavam ou se desligavam da escola.<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o Social<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os institutos federais de educa\u00e7\u00e3o, ci\u00eancia e tecnologia est\u00e3o autorizados a contratar docentes e t\u00e9cnicos administrativos para as escolas federais de educa\u00e7\u00e3o profissional em funcionamento no pa\u00eds. Portaria interministerial dos Minist\u00e9rios da Educa\u00e7\u00e3o e do Planejamento, Or\u00e7amento e Gest\u00e3o (MPOG), est\u00e1 publicada no Di\u00e1rio Oficial da Uni\u00e3o da segunda-feira, 25, altera anexos dos decretos do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-34748","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-inscricao","9":"category-oportunidades"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34748"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34749"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}