{"id":34750,"date":"2011-04-24T20:08:01","date_gmt":"2011-04-25T00:08:01","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34750"},"modified":"2011-04-24T23:11:01","modified_gmt":"2011-04-25T03:11:01","slug":"franca-oferece-bolsas-de-estudo-para-professores-da-rede-publica","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/franca-oferece-bolsas-de-estudo-para-professores-da-rede-publica\/34750","title":{"rendered":"Fran\u00e7a oferece bolsas de estudo para professores da rede p\u00fablica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34751\" title=\"bolsa estudo professor\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/bolsa-estudo-professor.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/bolsa-estudo-professor.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/bolsa-estudo-professor-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/bolsa-estudo-professor-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O Consulado Geral da Fran\u00e7a no Brasil est\u00e1 oferecendo duas <em><strong>bolsas de estudo para docentes<\/strong><\/em> do Ensino Fundamental, M\u00e9dio e Centro L\u00ednguas da rede p\u00fablica de S\u00e3o Paulo interessados em participar de um programa intensivo de est\u00e1gio voltado a professores de franc\u00eas.<\/p>\n<p>O curso ser\u00e1 promovido entre os dias 3 e 30 de julho deste ano, pelo Cavilam (Centre d&#8217;Approches Vivantes des Langues et des M\u00e9dias), na cidade francesa de Vichy. Os interessados em concorrer \u00e0s bolsas devem preencher o formul\u00e1rio dispon\u00edvel no site e envi\u00e1-lo at\u00e9 o dia 26 de abril para o consulado pelo e-mail ivone.figueiredo@diplomatie.gouv.fr.<\/p>\n<p>Para pleitear o benef\u00edcio, o candidato deve ser professor de franc\u00eas em atividade na rede p\u00fablica e membro da Associa\u00e7\u00e3o de Professores de Franc\u00eas do Estado de S\u00e3o Paulo (APFESP), com comprovante de pagamento da anuidade de 2011. Tamb\u00e9m \u00e9 requisito que o docente n\u00e3o tenha participado de programa de est\u00e1gio na Fran\u00e7a nos \u00faltimos cinco anos. A sele\u00e7\u00e3o ser\u00e1 feita por um j\u00fari formado por representantes do Consulado Franc\u00eas, da Secretaria de Estado da Educa\u00e7\u00e3o e da Associa\u00e7\u00e3o de Professores de Franc\u00eas do Estado.<\/p>\n<p>O interc\u00e2mbio faz parte de um acordo de coopera\u00e7\u00e3o lingu\u00edstica com o Brasil e tem por objetivo o aperfei\u00e7oamento do ensino do idioma no pa\u00eds. Al\u00e9m dos professores de S\u00e3o Paulo, concorrem ao benef\u00edcio docentes da rede p\u00fablica do Paran\u00e1, Santa Catarina e Rio Grande do Sul.<\/p>\n<p>Da Secretaria da Educa\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Consulado Geral da Fran\u00e7a no Brasil est\u00e1 oferecendo duas bolsas de estudo para docentes do Ensino Fundamental, M\u00e9dio e Centro L\u00ednguas da rede p\u00fablica de S\u00e3o Paulo interessados em participar de um programa intensivo de est\u00e1gio voltado a professores de franc\u00eas. O curso ser\u00e1 promovido entre os dias 3 e 30 de julho deste [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,351,370],"tags":[],"class_list":{"0":"post-34750","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-cursos","9":"category-inscricao"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34750"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34751"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}