{"id":34762,"date":"2011-04-25T20:30:02","date_gmt":"2011-04-26T00:30:02","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34762"},"modified":"2011-04-25T20:30:02","modified_gmt":"2011-04-26T00:30:02","slug":"lotofacil-629-%e2%80%93-resultado-do-sorteio-desta-segunda-feira-2504","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/lotofacil-629-%e2%80%93-resultado-do-sorteio-desta-segunda-feira-2504\/34762","title":{"rendered":"Lotof\u00e1cil 629 \u2013 resultado do sorteio desta segunda-feira (25\/04)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19231\" title=\"resultado da lotofacil\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotofacil.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotofacil.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotofacil-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotofacil-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Lotof\u00e1cil 629\u00a0\u2013 o\u00a0<strong><em>resultado<\/em><\/strong> do sorteio da <strong><em>Lotof\u00e1cil\u00a0629<\/em><\/strong>, realizado hoje, segunda-feira (<strong><em>25\/04<\/em><\/strong>), foi conferido pelos convidados para acompanhar o evento e divulgado em\u00a0Ribeir\u00e3o das Neves\/MG. No \u00faltimo sorteio o pr\u00eamio principal da Lotof\u00e1cil foi dividido entre 4 apostadores. O pr\u00eamio principal da Lotof\u00e1cil 629 de hoje estava estimado em 1,4\u00a0milh\u00f5es\u00a0de reais. O apostador que acertou de 11 a 15 dezenas poder\u00e1 receber pr\u00eamios de at\u00e9 R$ 800,00 em qualquer casa lot\u00e9rica credenciada ou nas ag\u00eancias da CAIXA, independente do valor. Confira o bilhete impresso pelo terminal. Ele \u00e9 o \u00fanico comprovante da sua aposta.<\/p>\n<p>Confira o\u00a0resultado da Lotof\u00e1cil 629\u00a0desta segunda-feira (25\/04):<\/p>\n<p>01\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a002\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a004\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a005\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a006<\/p>\n<p>07\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a009\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a012\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a014\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a015<\/p>\n<p>17\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a019\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a021\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a025<\/p>\n<p>A Lotof\u00e1cil \u00e9 o jogo certo para voc\u00ea que gosta de apostar e, principalmente, ganhar. Com apenas R$ 2,50, voc\u00ea marca 15 n\u00fameros entre os 25 dispon\u00edveis no volante. E fatura o pr\u00eamio se acertar 11, 12, 13, 14 ou 15 n\u00fameros. S\u00e3o muitas chances de ganhar.<\/p>\n<p>Voc\u00ea pode deixar ainda que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 2, 4 ou 8 concursos consecutivos (Teimosinha). Os sorteios s\u00e3o realizados \u00e0s segundas e quintas, sempre \u00e0s 20h.<\/p>\n<p>O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o, j\u00e1 computado o adicional destinado ao Minist\u00e9rio do Esporte. Dessa porcentagem, ser\u00e1 deduzido o pagamento dos pr\u00eamios com valores fixos:<\/p>\n<p>R$ 2,50 para as apostas com 11 progn\u00f3sticos certos entre os 15 sorteados;<\/p>\n<p>R$ 5,00 para as apostas com 12 progn\u00f3sticos certos entre os 15 sorteados;<\/p>\n<p>R$ 12,50 para as apostas com 13 progn\u00f3sticos certos entre os 15 sorteados.<\/p>\n<p>Somente ap\u00f3s a apura\u00e7\u00e3o dos ganhadores dos pr\u00eamios com valores fixos, o valor restante do total destinado \u00e0 premia\u00e7\u00e3o ser\u00e1 distribu\u00eddo para as demais faixas de pr\u00eamios nos seguintes porcentuais:<\/p>\n<p>70% entre os acertadores de 15 n\u00fameros;<\/p>\n<p>30% entre os acertadores de 14 n\u00fameros entre os 15 sorteados.<\/p>\n<p>N\u00e3o havendo ganhador em qualquer faixa de premia\u00e7\u00e3o, o valor acumula para o concurso seguinte, na faixa de pr\u00eamio com 15 acertos. N\u00e3o deixe de conferir o seu bilhete de aposta.\u00a0Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotof\u00e1cil 629\u00a0\u2013 o\u00a0resultado do sorteio da Lotof\u00e1cil\u00a0629, realizado hoje, segunda-feira (25\/04), foi conferido pelos convidados para acompanhar o evento e divulgado em\u00a0Ribeir\u00e3o das Neves\/MG. No \u00faltimo sorteio o pr\u00eamio principal da Lotof\u00e1cil foi dividido entre 4 apostadores. O pr\u00eamio principal da Lotof\u00e1cil 629 de hoje estava estimado em 1,4\u00a0milh\u00f5es\u00a0de reais. O apostador que acertou de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,335,357],"tags":[],"class_list":{"0":"post-34762","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-loto-facil"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34762"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/19231"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}