{"id":34790,"date":"2011-04-26T19:51:39","date_gmt":"2011-04-26T23:51:39","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34790"},"modified":"2011-04-26T19:51:39","modified_gmt":"2011-04-26T23:51:39","slug":"avon-voices-comeca-a-votacao-nas-cantoras-favoritas","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/avon-voices-comeca-a-votacao-nas-cantoras-favoritas\/34790","title":{"rendered":"Avon Voices &#8211; come\u00e7a a vota\u00e7\u00e3o nas cantoras favoritas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34791\" title=\"avon voice\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/avon-voice.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/avon-voice.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/avon-voice-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/avon-voice-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Avon Voices &#8211; pessoas do mundo todo est\u00e3o convidadas a dar o seu voto para eleger as <em><strong>cantoras<\/strong><\/em> favoritas no <em><strong>Avon Voices<\/strong><\/em>, a primeira busca online global de talentos da m\u00fasica promovida pela Avon. As 175 candidatas de mais de 50 pa\u00edses, entre elas revendedoras Avon, conclu\u00edram as sess\u00f5es de grava\u00e7\u00e3o profissional em Nashville, Paris, Hong Kong e Rio de Janeiro, realizadas ao longo do m\u00eas de abril. Estas performances j\u00e1 est\u00e3o dispon\u00edveis no site <em><strong><a href=\"http:\/\/www.avonvoices.com\" target=\"_blank\">www.avonvoices.com<\/a><\/strong><\/em> para que os internautas possam assistir, decidir e votar. Essa vota\u00e7\u00e3o popular on-line e as notas dadas pelo j\u00fari composto por celebridades mundiais da m\u00fasica ser\u00e3o a base para a escolha das duas mulheres, sendo uma delas uma revendedora Avon, que ser\u00e3o celebradas globalmente na internet e ter\u00e3o a oportunidade de gravar, nos Estados Unidos, um disco profissional.<\/p>\n<p>O Brasil \u00e9 o segundo pa\u00eds com maior n\u00famero de selecionadas. H\u00e1 11 brasileiras participando da busca de talento, representando os estados de S\u00e3o Paulo, Rio de Janeiro, Minas Gerais, Alagoas, Bahia, Santa Catarina e Rio Grande do Sul. S\u00e3o Paulo \u00e9 o estado com maior n\u00famero de selecionadas, em n\u00famero de quatro. \u00c9 seguido por Minas Gerais, com duas. Os demais cinco estados contam com uma participante cada.<\/p>\n<p>Confira as cantoras brasileiras que est\u00e3o participando:<\/p>\n<p>Alessandra de Martino Lungano, S\u00e3o Paulo (SP)<br \/>\nAnna Cristina de Souza Zanetti, Jaragu\u00e1 do Sul (SC)<br \/>\nLouise Cardoso Hug, Niter\u00f3i (RJ)<br \/>\nNaiana Papini Campos, Belo Horizonte (MG)<br \/>\nPamela Luyza, Uberaba (MG)<br \/>\nPauline Alencar, Macei\u00f3 (AL)<br \/>\nQuinara Santana Vizeu, Porto Alegre (RS)<br \/>\nRenata Santos Leal, S\u00e3o Paulo (SP)<br \/>\nRita Cristina Pithon Costa, Vit\u00f3ria da Conquista (BA)<br \/>\nRuthe Gl\u00f3ria Sergio Ramos, S\u00e3o Paulo (SP)<br \/>\nTha\u00eds Rodrigues Horta Ferreira, S\u00e3o Paulo (SP)<\/p>\n<p>A cantora Ivete Sangalo \u00e9 a \u00fanica artista brasileira a integrar o j\u00fari de celebridades da m\u00fasica mundial, que inclui a cantora americana Fergie, do grupo Black Eyed Peas, vencedora de seis pr\u00eamios Grammy; a celebrada compositora americana Diane Warren; a cantora e compositora pop brit\u00e2nica Natasha Bedingfield, indicada para o Grammy; a cantora e atriz filipina Lea Salonga; a cantora russa Valeriya, sensa\u00e7\u00e3o em seu pa\u00eds; Delta Goodrem, eleita artista da d\u00e9cada na Austr\u00e1lia; a percussionista alem\u00e3 Sheila E., indicada para o Grammy; o cantor e produtor musical americano David Pack, ganhador de um Grammy; o cantor e compositor argentino Diego Torres, indicado ao Grammy; e Maia, hoje uma das estrelas colombianas da can\u00e7\u00e3o.<\/p>\n<p>Ap\u00f3s esta fase de vota\u00e7\u00e3o, at\u00e9 100 candidatas passar\u00e3o para a pr\u00f3xima etapa. A seguir, no m\u00e1ximo 25 semifinalistas ser\u00e3o escolhidas para estar na terceira rodada. O programa ser\u00e1 conclu\u00eddo no quarto trimestre do ano, quando at\u00e9 10 finalistas competir\u00e3o pelas \u00faltimas duas vagas t\u00e3o desejadas. (categoria Geral e categoria Revendedora Avon).<\/p>\n<p>Lan\u00e7ado em comemora\u00e7\u00e3o ao anivers\u00e1rio de 125 anos da empresa, Avon Voices j\u00e1 atraiu mais de um milh\u00e3o de visitantes de 190 pa\u00edses, que visitaram o site www.avonvoices.com. As candidatas que participam da fase atual foram selecionadas dentre um grupo de mais de 6 mil participantes de 62 pa\u00edses, que come\u00e7aram a enviar seus v\u00eddeos em dezembro do ano passado.<\/p>\n<p>&#8220;A m\u00fasica destas mulheres de talento vem do fundo do cora\u00e7\u00e3o; suas vozes e suas hist\u00f3rias servir\u00e3o de inspira\u00e7\u00e3o para o mundo inteiro,&#8221; afirma Joe Billone, vice-presidente mundial de Comunica\u00e7\u00e3o de Vendas da Avon e criador do projeto. &#8220;Avon Voices \u00e9 mais do que uma busca de talentos: \u00e9 uma celebra\u00e7\u00e3o! Durante 125 anos, a miss\u00e3o da Avon tem sido dar \u00e0s mulheres oportunidade para transformar sonhos em realidade. Avon Voices est\u00e1 contribuindo para cumprirmos esse compromisso.&#8221;<\/p>\n<p>Hino global vai apoiar a causa do combate \u00e0 viol\u00eancia dom\u00e9stica<\/p>\n<p>No encerramento do programa, as finalistas mundiais e as celebridades que participaram do j\u00fari do Avon Voices gravar\u00e3o um hino composto por Diane Warren. Ele ser\u00e1 apresentado ao vivo pela primeira vez durante o Jantar Anual de Gala da Funda\u00e7\u00e3o Avon para Mulheres, realizado em Nova Iorque, em novembro. Neste evento ser\u00e3o tamb\u00e9m anunciados os nomes das vencedoras. O hino estar\u00e1 dispon\u00edvel para compra nos sites www.avonvoices.com e www.studioXOXO.com. As m\u00fasicas Shoot for the Stars, escrita e interpretada por Natasha Bedingfield, e Until You Love You, composi\u00e7\u00e3o de Diane Warren e produ\u00e7\u00e3o de David Pack, cantada por Valeriya, s\u00e3o algumas das m\u00fasicas gravadas pelos representantes do j\u00fari do Avon Voices e por outros artistas, dispon\u00edveis para compra nos EUA.<\/p>\n<p>Parte dos fundos arrecadados com a venda de todas essas grava\u00e7\u00f5es ser\u00e1 doada para a campanha global da Avon Foundation cujo objetivo \u00e9 combater a viol\u00eancia contra mulheres. At\u00e9 o momento, os programas sociais da Avon em todo o mundo j\u00e1 arrecadaram e entregaram mais de US$ 30 milh\u00f5es para projetos de conscientiza\u00e7\u00e3o, educa\u00e7\u00e3o, servi\u00e7os diretos e preven\u00e7\u00e3o contra a viol\u00eancia dom\u00e9stica e de g\u00eanero.<\/p>\n<p>Inscreva-se j\u00e1!<\/p>\n<p>Os v\u00eddeos das cantoras participantes de Avon Voices j\u00e1 podem ser vistos por todos os visitantes do site. Para votar, \u00e9 preciso se cadastrar no site e confirmar a inscri\u00e7\u00e3o clicando no e-mail enviado pela produ\u00e7\u00e3o do evento.<\/p>\n<p>Assista e vote: Confira os v\u00eddeos das participantes, com performances gravadas por equipes profissionais contratadas pela Avon, e vote nas suas favoritas. A competi\u00e7\u00e3o fica mais acirrada a partir de agora, com o desenrolar das quatro etapas eliminat\u00f3rias, nas quais as participantes s\u00e3o selecionadas por meio da combina\u00e7\u00e3o de votos do p\u00fablico enviados pela Internet e a pontua\u00e7\u00e3o dada pelos jurados.<\/p>\n<p>Componha: A partir de 20 de maio, homens e mulheres podem concorrer, individualmente ou em grupo, na competi\u00e7\u00e3o de compositores. Escreva uma can\u00e7\u00e3o original que inspire ou traga esperan\u00e7a e otimismo para o mundo. Basta enviar uma grava\u00e7\u00e3o digital da can\u00e7\u00e3o e a letra para o site www.avonvoices.com (de 20 de maio a 1\u00b0 de julho de 2011).<\/p>\n<p>Saiba mais sobre Avon Voices acessando o site oficial www.avonvoices.com e fazendo seu registro. Voc\u00ea ser\u00e1 informado sobre tudo o que acontece.<\/p>\n<p>No endere\u00e7o <a href=\"http:\/\/www.multivu.com\/players\/English\/45814-avon-voices \" target=\"_blank\">http:\/\/www.multivu.com\/players\/English\/45814-avon-voices<\/a> voc\u00ea poder\u00e1 ainda assistir aos v\u00eddeos dos jurados, ter acesso a releases, fotos e outros materiais.<\/p>\n<p>Na rede social, todos s\u00e3o convidados a seguir Avon Voices no Facebook www.facebook.com\/avonvoices e no Twitter www.twitter.com\/avonvoices<\/p>\n<p>Para ter acesso a todas as fotos da coletiva com Ivete Sangalo, realizada no dia 16 de abril, acesse o seguinte endere\u00e7o &#8211; <a href=\"http:\/\/www.flickr.com\/photos\/avonvoicesbrasil\/\" target=\"_blank\">www.flickr.com\/photos\/avonvoicesbrasil\/<\/a><\/p>\n<p>Sobre a Avon<br \/>\nCelebrando 125 anos de atividade, a Avon, a empresa voltada para as mulheres, \u00e9 l\u00edder mundial no mercado de beleza, com uma receita anual de mais de US$ 10 bilh\u00f5es. Como a maior empresa de vendas diretas do mundo, comercializa seus produtos em mais de 100 pa\u00edses por interm\u00e9dio de aproximadamente 6,5 milh\u00f5es de revendedores aut\u00f4nomos. A linha de produtos Avon inclui itens de beleza de alta tecnologia, assim como produtos de moda e para casa, e apresenta marcas de qualidade reconhecida como Avon Color, Renew, Skin-So-Soft, Advance Techniques, Avon Naturals e Mark. Para obter mais informa\u00e7\u00f5es sobre a Avon e seus produtos, visite o site www.avoncompany.com.<\/p>\n<p>A empresa est\u00e1 no Brasil h\u00e1 53 anos e atualmente conta com mais de 1,1 milh\u00e3o de revendedores aut\u00f4nomos, comercializando os produtos Avon em todo o pa\u00eds. A cada campanha de venda, que dura em m\u00e9dia 19 dias, os revendedores interagem com milh\u00f5es de brasileiros e suas fam\u00edlias, levando beleza e desenvolvendo relacionamentos. A Avon Brasil possui uma f\u00e1brica na cidade de S\u00e3o Paulo e tr\u00eas centros de distribui\u00e7\u00e3o nos estados de S\u00e3o Paulo, Cear\u00e1 e Bahia. A empresa mant\u00e9m h\u00e1 seis anos o Instituto Avon (www.institutoavon.org.br) e lan\u00e7ou dois importantes programas de responsabilidade social nos \u00faltimos anos: o Fundo Viva Amanh\u00e3 (www.vivaoamanha.com.br), em 2007, e o Viva o Amanh\u00e3 mais Verde, em 2009. Para saber mais sobre a Avon Brasil acesse www.avon.com.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avon Voices &#8211; pessoas do mundo todo est\u00e3o convidadas a dar o seu voto para eleger as cantoras favoritas no Avon Voices, a primeira busca online global de talentos da m\u00fasica promovida pela Avon. As 175 candidatas de mais de 50 pa\u00edses, entre elas revendedoras Avon, conclu\u00edram as sess\u00f5es de grava\u00e7\u00e3o profissional em Nashville, Paris, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22],"tags":[],"class_list":{"0":"post-34790","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34790"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34791"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}