{"id":34792,"date":"2011-04-26T19:57:46","date_gmt":"2011-04-26T23:57:46","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34792"},"modified":"2011-04-26T19:57:46","modified_gmt":"2011-04-26T23:57:46","slug":"tv-cultura-estreia-falar-ingles-e-brincadeira","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/tv-cultura-estreia-falar-ingles-e-brincadeira\/34792","title":{"rendered":"TV Cultura estreia: Falar ingl\u00eas \u00e9 brincadeira"},"content":{"rendered":"<p><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34793\" title=\"falar ingles tv cultura\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/falar-ingles-tv-cultura.jpg\" alt=\"\" width=\"301\" height=\"194\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/falar-ingles-tv-cultura.jpg 301w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/falar-ingles-tv-cultura-250x161.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/falar-ingles-tv-cultura-150x96.jpg 150w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/>Falar ingl\u00eas \u00e9 brincadeira<\/strong><\/em> &#8211; programa de sucesso da <em><strong>TV Cultura<\/strong><\/em> entre 1969 e 1981, <em><strong>Ingl\u00eas com M\u00fasica<\/strong><\/em> foi  revivido no ano passado e, agora, volta em novo formato, com estrutura de game  show. A proposta \u00e9 incentivar o aprendizado do idioma de forma leve e divertida,  usando letras de m\u00fasicas e jogos entre equipes. Vai ao ar na TV Cultura, de  segunda a sexta-feira, \u00e0s 18h. Aos s\u00e1bados, \u00e0s 12h, \u00e9 exibida a edi\u00e7\u00e3o completa  da semana.<\/p>\n<p>A nova temporada traz a atriz e cantora Amanda Acosta e a professora Marisa  Leite de Barros, apresentadora e criadora da vers\u00e3o original da atra\u00e7\u00e3o. Amanda  apresenta a m\u00fasica do dia, acompanhada de sua banda, formada por Serginho  Carvalho (baixo), Adriano Trindade (baterista) e do Agenor de Lorenzi  (teclados).<\/p>\n<p>A partir da\u00ed come\u00e7a a brincadeira, que vai desde um trava-l\u00ednguas em ingl\u00eas,  para descontrair, at\u00e9 os desafios dos games, que envolvem e ensinam os  participantes: equipes formadas por estudantes das Escolas T\u00e9cnicas (Etecs) e  das Faculdades de Tecnologia (Fatecs) de S\u00e3o Paulo.<\/p>\n<p>O programa de audit\u00f3rio \u00e9 uma parceria da Univesp TV (canal digital 2.2 da  Funda\u00e7\u00e3o Padre Anchieta) com o Centro Paula Souza.<\/p>\n<p>Novo quadro<br \/>\nTalent Show nasceu por acaso. Alunos que em programas  anteriores se deram bem no palco s\u00e3o agora convidados para cantar numa esp\u00e9cie  de show de calouros. A cada edi\u00e7\u00e3o, tr\u00eas estudantes se apresentam, s\u00e3o avaliados  na pron\u00fancia, na banda e na apresenta\u00e7\u00e3o geral. Desses, um \u00e9 selecionado. No  final do m\u00eas, apresentam-se os quatro semifinalistas, saindo um vencedor, com  direito a trof\u00e9u do programa.<\/p>\n<p>INGL\u00caS COM M\u00daSICA<br \/>\nExibi\u00e7\u00e3o \u2013 TV Cultura: segunda a sexta-feira, \u00e0s 18h.  S\u00e1bados, \u00e0s 12h<br \/>\nExibi\u00e7\u00e3o \u2013 Univesp TV (canal digital 2.2 da Funda\u00e7\u00e3o Padre  Anchieta): de segunda a sexta-feira \u00e0s 20h45, e aos s\u00e1bados \u00e0s 12h.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falar ingl\u00eas \u00e9 brincadeira &#8211; programa de sucesso da TV Cultura entre 1969 e 1981, Ingl\u00eas com M\u00fasica foi revivido no ano passado e, agora, volta em novo formato, com estrutura de game show. A proposta \u00e9 incentivar o aprendizado do idioma de forma leve e divertida, usando letras de m\u00fasicas e jogos entre equipes. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,343],"tags":[],"class_list":{"0":"post-34792","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-televisao"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34792"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34793"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}