{"id":34882,"date":"2011-05-01T19:39:53","date_gmt":"2011-05-01T23:39:53","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34882"},"modified":"2011-05-01T19:39:53","modified_gmt":"2011-05-01T23:39:53","slug":"tele-sena-de-maes-2011-%e2%80%93-resultado-do-segundo-sorteio","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/tele-sena-de-maes-2011-%e2%80%93-resultado-do-segundo-sorteio\/34882","title":{"rendered":"Tele Sena de M\u00e3es 2011 \u2013 resultado do segundo sorteio"},"content":{"rendered":"<p><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34633\" title=\"tele sena resultado\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/tele-sena-resultado.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/tele-sena-resultado.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/tele-sena-resultado-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/tele-sena-resultado-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Tele Sena de M\u00e3es<\/strong><\/em> 2011 &#8211; neste domingo (01\/05), o SBT apresentou o <em><strong>resultado<\/strong><\/em> do segundo <em><strong>sorteio<\/strong><\/em> da Tele Sena de M\u00e3es (2011). Com o slogan \u201cTele Sena: agora com quatro chances no Ganhe J\u00e1!\u201d, a Lideran\u00e7a Capitaliza\u00e7\u00e3o colocou no ar a campanha para a Tele Sena de M\u00e3es, com a participa\u00e7\u00e3o especial da atriz Giulia Gam. A novidade desta edi\u00e7\u00e3o \u00e9 a Quadra da Sorte, com a qual os consumidores podem concorrer a pr\u00eamios instant\u00e2neos como casa, carros, motos e premia\u00e7\u00f5es em dinheiro. Na campanha a atriz Giulia Gam explica as vantagens e as chances de ganhar com a Tele Sena de M\u00e3es.<\/p>\n<p>Confira o resultado do segundo sorteio da Tele Sena de M\u00e3es (01\/05):<\/p>\n<p>12 \u00a0 13 \u00a0 \u00a015 \u00a0 \u00a027 \u00a0 \u00a029<\/p>\n<p>Confira o resultado do primeiro sorteio da Tele Sena de M\u00e3es (<a href=\"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/tele-sena-de-maes-2011-%E2%80%93-resultado-do-primeiro-sorteio\/34743\">clique aqui<\/a>)<\/p>\n<p>A Tele Sena de M\u00e3es est\u00e1 distribuindo mais de 30 mil pr\u00eamios. Al\u00e9m dos pr\u00eamios instant\u00e2neos, o cliente concorre com dois quadros impressos no t\u00edtulo. O primeiro corresponde \u00e0 premia\u00e7\u00e3o para Mais Pontos e Menos Pontos, com sorteios semanais aos domingos. Dessa forma, quem marcar mais pontos no sorteio final receber\u00e1 at\u00e9 Meio Milh\u00e3o de Reais e aquele que fizer menos pontos ganhar\u00e1 at\u00e9 R$ 200 mil. J\u00e1 o segundo quadro se refere \u00e0 Tele Sena Completa, que ter\u00e1 um sorteio \u00fanico. Assim, quem completar o quadro pode receber at\u00e9 R$ 400 mil. Se houver mais de um ganhador, o pr\u00eamio ser\u00e1 dividido em partes iguais.<\/p>\n<p>O t\u00edtulo de capitaliza\u00e7\u00e3o Tele Sena dever\u00e1 ser conferido nas lot\u00e9ricas e poder\u00e1 ser resgatado ap\u00f3s 12 meses (conforme a data prevista na Tele Sena no campo \u201cATEN\u00c7\u00c3O\u201d, impresso na parte externa do t\u00edtulo), bastando apresent\u00e1-lo em Casas Lot\u00e9ricas ou Ag\u00eancias dos Correios. O resgate corresponder\u00e1 a 50% do valor pago, atualizado monetariamente pela taxa de remunera\u00e7\u00e3o b\u00e1sica aplicada \u00e0 poupan\u00e7a e por juros.<\/p>\n<p>Tele Sena de M\u00e3es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tele Sena de M\u00e3es 2011 &#8211; neste domingo (01\/05), o SBT apresentou o resultado do segundo sorteio da Tele Sena de M\u00e3es (2011). Com o slogan \u201cTele Sena: agora com quatro chances no Ganhe J\u00e1!\u201d, a Lideran\u00e7a Capitaliza\u00e7\u00e3o colocou no ar a campanha para a Tele Sena de M\u00e3es, com a participa\u00e7\u00e3o especial da atriz [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,335,356],"tags":[],"class_list":{"0":"post-34882","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-tele-sena"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34882"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34633"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}