{"id":35090,"date":"2011-05-16T09:16:02","date_gmt":"2011-05-16T13:16:02","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=35090"},"modified":"2011-05-16T09:16:02","modified_gmt":"2011-05-16T13:16:02","slug":"massa-polar-ganha-forca-e-frio-chegara-ate-o-norte-do-brasil","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/massa-polar-ganha-forca-e-frio-chegara-ate-o-norte-do-brasil\/35090","title":{"rendered":"Massa polar ganha for\u00e7a e frio chegar\u00e1 at\u00e9 o Norte do Brasil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28410\" title=\"previsao do tempo temperatura\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A <em><strong>massa de ar polar<\/strong><\/em> que atua no Sul do Pa\u00eds desde a semana passada ganha  for\u00e7a e agora avan\u00e7a para o Sudeste, Centro-Oeste e at\u00e9 Norte do Pa\u00eds. De acordo  com os meteorologistas da SOMAR, o <em><strong>frio<\/strong><\/em> ainda ser\u00e1 mais acentuado na Regi\u00e3o Sul,  onde h\u00e1 previs\u00e3o de <em><strong>temperaturas<\/strong><\/em> negativas a partir desta ter\u00e7a-feira na regi\u00e3o  serrana de Santa Catarina.<\/p>\n<p>A maior quantidade de nuvens geradas pelos ventos \u00famidos do mar tamb\u00e9m deixam  as temperaturas baixas e acentuam a sensa\u00e7\u00e3o de frio no leste de S\u00e3o Paulo e no  Rio de Janeiro nesta primeira metade da semana. J\u00e1 o interior paulista e de  Minas Gerais ser\u00e3o marcados por noites e madrugadas frias, mas com dias de sol  que deixam as tardes agrad\u00e1veis.<br \/>\nNo Centro-Oeste, o frio ser\u00e1 sentido mais  sobre o Mato Grosso do Sul, com m\u00ednimas em torno de 10\u00b0C ao longo desta semana.  No Norte, a temperatura cai apenas no sul de Rond\u00f4nia e n\u00e3o chega a fazer tanto  frio como no come\u00e7o do m\u00eas (em especial no dia 4 de maio).<\/p>\n<p>Nova onda de frio chega ao pa\u00eds na pr\u00f3xima semana<br \/>\nSegundo os  meteorologistas da SOMAR, uma segunda massa de ar polar avan\u00e7a pelo Brasil em 24  de maio e mant\u00e9m as temperaturas baixas at\u00e9 o fim do m\u00eas nos tr\u00eas Estados da  Regi\u00e3o Sul. No Sudeste e no Centro-Oeste, a temperatura cai novamente depois do  dia 26 de maio.<\/p>\n<p>Dias seguem quentes no Norte e Nordeste<br \/>\nAt\u00e9 o fim do m\u00eas as temperaturas  permanecer\u00e3o altas (acima dos 30\u00b0C) em grande parte das Regi\u00f5es Norte e  Nordeste.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A massa de ar polar que atua no Sul do Pa\u00eds desde a semana passada ganha for\u00e7a e agora avan\u00e7a para o Sudeste, Centro-Oeste e at\u00e9 Norte do Pa\u00eds. De acordo com os meteorologistas da SOMAR, o frio ainda ser\u00e1 mais acentuado na Regi\u00e3o Sul, onde h\u00e1 previs\u00e3o de temperaturas negativas a partir desta ter\u00e7a-feira [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,327,376],"tags":[],"class_list":{"0":"post-35090","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-clima","9":"category-clima-brasil"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=35090"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/28410"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=35090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=35090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=35090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}