{"id":35105,"date":"2011-05-17T10:17:35","date_gmt":"2011-05-17T14:17:35","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=35105"},"modified":"2011-05-17T10:17:35","modified_gmt":"2011-05-17T14:17:35","slug":"inflacao-aumenta-em-cinco-das-sete-capitais-pesquisadas-pela-fgv","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/inflacao-aumenta-em-cinco-das-sete-capitais-pesquisadas-pela-fgv\/35105","title":{"rendered":"Infla\u00e7\u00e3o aumenta em cinco das sete capitais pesquisadas pela FGV"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34916\" title=\"inflacao\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/inflacao.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/inflacao.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/inflacao-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/inflacao-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Rio de Janeiro &#8211; A <em><strong>infla\u00e7\u00e3o<\/strong><\/em> medida pelo \u00cdndice de Pre\u00e7os ao Consumidor Semanal (IPC-S) aumentou em cinco das sete capitais pesquisadas pela Funda\u00e7\u00e3o Getulio Vargas (FGV). Apenas o Rio de Janeiro e Bras\u00edlia registraram alta menos intensa nos pre\u00e7os entre as semanas do dia 7 e 15 de maio.<\/p>\n<p>De acordo com comunicado divulgado hoje (17) pela FGV, o IPC-S diminuiu de 1,18% para 1,08% na capital fluminense. O resultado reflete as redu\u00e7\u00f5es em seis das sete classes de despesa componentes do IPC-S, principalmente vestu\u00e1rio (de 2,80% para 1,62%) e educa\u00e7\u00e3o, leitura e recrea\u00e7\u00e3o (de 0,47% para varia\u00e7\u00e3o nula).<\/p>\n<p>J\u00e1 na capital federal o IPC-S caiu de 0,50% para 0,47%. Neste caso, o movimento foi influenciado pela alta menos intensa nos pre\u00e7os dos transportes (de 1,44% para 0,83%) e de vestu\u00e1rio (de 1,43% para 1,19%).<\/p>\n<p>No mesmo per\u00edodo, as demais capitais registraram aumento da infla\u00e7\u00e3o. Em pontos percentuais, as eleva\u00e7\u00f5es foram mais intensas em Salvador (de 0,97% para 1,20%), em Belo Horizonte (de 1,32% para 1,53%) e em Recife (de 1% para 1,12%).<\/p>\n<p>Em S\u00e3o Paulo, capital com maior peso na forma\u00e7\u00e3o do IPC-S, a infla\u00e7\u00e3o passou de 0,97% para 1,01%, com acr\u00e9scimo de 0,04 ponto percentual; e em Porto Alegre, tamb\u00e9m com aumento de 0,04 ponto percentual, os pre\u00e7os subiram 0,89%, depois de terem eleva\u00e7\u00e3o de 0,85% na semana anterior.<\/p>\n<p>De acordo com a Funda\u00e7\u00e3o Getulio Vargas, o IPC-S da segunda pr\u00e9via de maio foi 1,09%. O indicador ficou 0,04 ponto percentual acima do dado da apura\u00e7\u00e3o anterior (1,05%). A principal eleva\u00e7\u00e3o foi constatada no grupo alimenta\u00e7\u00e3o (de 1,26% para 1,52%). De um total de 21 g\u00eaneros aliment\u00edcios pesquisados, 14 ficaram mais caros, entre eles as hortali\u00e7as e os legumes (de 5,77% para 7,89%); as frutas (de 0,12% para 0,33%); os latic\u00ednios (de 2,72% para 2,84%), e a comida pronta e congelados (de 1,05% para 1,26%).<\/p>\n<p>A divulga\u00e7\u00e3o do pr\u00f3ximo levantamento de pre\u00e7os ser\u00e1 no dia 24 de maio.<\/p>\n<p>Thais Leit\u00e3o<br \/>\nRep\u00f3rter da Ag\u00eancia Brasil<br \/>\nEdi\u00e7\u00e3o: Juliana Andrade<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rio de Janeiro &#8211; A infla\u00e7\u00e3o medida pelo \u00cdndice de Pre\u00e7os ao Consumidor Semanal (IPC-S) aumentou em cinco das sete capitais pesquisadas pela Funda\u00e7\u00e3o Getulio Vargas (FGV). Apenas o Rio de Janeiro e Bras\u00edlia registraram alta menos intensa nos pre\u00e7os entre as semanas do dia 7 e 15 de maio. De acordo com comunicado divulgado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,7],"tags":[],"class_list":{"0":"post-35105","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=35105"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34916"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=35105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=35105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=35105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}