{"id":35134,"date":"2011-05-18T21:11:41","date_gmt":"2011-05-19T01:11:41","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=35134"},"modified":"2011-05-18T21:11:41","modified_gmt":"2011-05-19T01:11:41","slug":"quina-2599-%e2%80%93-resultado-do-sorteio-desta-quarta-feira-1805","status":"publish","type":"post","link":"https:\/\/migracao.redenoticia.com.br\/noticia\/2011\/quina-2599-%e2%80%93-resultado-do-sorteio-desta-quarta-feira-1805\/35134","title":{"rendered":"Quina 2599 \u2013 resultado do sorteio desta quarta-feira (18\/05)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19275\" title=\"resultado da quina\" src=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-quina1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-quina1.jpg 300w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-quina1-250x160.jpg 250w, https:\/\/migracao.redenoticia.com.br\/noticia\/imagens\/resultado-da-quina1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Quina 2599 \u2013 o\u00a0<strong><em>resultado<\/em><\/strong> da\u00a0<strong><em>Quina\u00a02599<\/em><\/strong>, sorteio desta quarta-feira (<strong><em>18\/05<\/em><\/strong>), foi divulgado pelo caminh\u00e3o da sorte em Vit\u00f3ria da Conquista\/BA. O pr\u00eamio principal do \u00faltimo sorteio acumulou. O pr\u00eamio principal da Quina 2599 de hoje estava estimado em 1,3 milh\u00e3o de reais. Na Quina, voc\u00ea aposta em 5, 6 ou 7 n\u00fameros, entre os 80 dispon\u00edveis, e fatura um pr\u00eamio milion\u00e1rio. Voc\u00ea ganha se acertar 3, 4 ou 5 n\u00fameros. E pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 3, 6, 12, 18 ou 24 concursos consecutivos (Teimosinha).<\/p>\n<p>Confira o resultado da Quina 2599 desta quarta-feira (18\/05):<\/p>\n<p><strong> 16\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a031\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a036\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a044\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a068<\/strong><\/p>\n<p>O concurso da\u00a0<strong>Quina<\/strong> teve\u00a0<strong>1<\/strong> ganhador que levou o pr\u00eamio principal de\u00a0<strong>R$ 1.340.995,62.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>O pre\u00e7o da aposta da loteria Quina em 5 n\u00fameros \u00e9 de R$ 0, 75, mas voc\u00ea pode pagar R$ 3,00 e concorrer com 6 n\u00fameros ou pagar R$ 7,50 e concorrer com 7 n\u00fameros. Aumente as suas chances de ganhar! O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o, j\u00e1 computado o adicional destinado ao Minist\u00e9rio do Esporte. Dessa porcentagem, s\u00e3o distribu\u00eddos: 40% entre os acertadores dos 5 n\u00fameros sorteados (Quina); 30% entre os acertadores de 4 n\u00fameros (Quadra); 30% entre os acertadores de 3 n\u00fameros (Terno). Ap\u00f3s o resultado do sorteio da Quina, n\u00e3o havendo acertador em qualquer faixa de premia\u00e7\u00e3o, o valor acumula para o concurso seguinte, na respectiva faixa de premia\u00e7\u00e3o. N\u00e3o deixe de conferir o seu bilhete de aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quina 2599 \u2013 o\u00a0resultado da\u00a0Quina\u00a02599, sorteio desta quarta-feira (18\/05), foi divulgado pelo caminh\u00e3o da sorte em Vit\u00f3ria da Conquista\/BA. O pr\u00eamio principal do \u00faltimo sorteio acumulou. O pr\u00eamio principal da Quina 2599 de hoje estava estimado em 1,3 milh\u00e3o de reais. Na Quina, voc\u00ea aposta em 5, 6 ou 7 n\u00fameros, entre os 80 dispon\u00edveis, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[22,335,358],"tags":[],"class_list":{"0":"post-35134","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-quina"},"_links":{"self":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=35134"}],"version-history":[{"count":0,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/19275"}],"wp:attachment":[{"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=35134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=35134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migracao.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=35134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}